{"id":19571,"date":"2025-03-04T16:38:30","date_gmt":"2025-03-04T16:38:30","guid":{"rendered":"https:\/\/www.naturenb.ca\/?p=19571"},"modified":"2025-03-06T13:23:58","modified_gmt":"2025-03-06T13:23:58","slug":"compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques","status":"publish","type":"post","link":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/","title":{"rendered":"Compter tous les canards d&rsquo;hiver : surveillance des sauvagines et migrants arctiques"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/naturenb.ca\/category\/nb-fieldnotes\"><img loading=\"lazy\" decoding=\"async\" width=\"923\" height=\"348\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2024\/02\/Artboard-3-copy@2x.png\" alt=\"\" class=\"wp-image-16050\" style=\"width:606px;height:auto\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2024\/02\/Artboard-3-copy@2x.png 923w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2024\/02\/Artboard-3-copy@2x-300x113.png 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2024\/02\/Artboard-3-copy@2x-768x290.png 768w\" sizes=\"auto, (max-width: 923px) 100vw, 923px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Compter tous les canards d&rsquo;hiver : surveillance des sauvagines et migrants arctiques<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Depuis que j&rsquo;ai commenc\u00e9 \u00e0 m&rsquo;int\u00e9resser plus s\u00e9rieusement aux oiseaux, les oiseaux aquatiques m&rsquo;ont toujours un peu intimid\u00e9. Tant de canards \u00e0 apprendre, si peu de temps, me disais-je ! Jusqu&rsquo;\u00e0 ce que je r\u00e9alise que j&rsquo;ai toute la vie devant moi pour apprendre \u00e0 les conna\u00eetre. Je me suis donc rendu \u00e0 Saint John pour en apprendre davantage sur les enqu\u00eates relatives aux oiseaux d&rsquo;eau, en suivant ma coll\u00e8gue Lauren au Recensement des oiseaux aquatiques du port de Saint John. Au cours de mes recherches, j&rsquo;ai appris que plusieurs des sauvagines (oiseaux aquatiques migrateurs) et de nombreux autres oiseaux qu&rsquo;on voit ici l&rsquo;hiver passaient l&rsquo;\u00e9t\u00e9 dans l&rsquo;Arctique. C&rsquo;est ainsi que j&rsquo;ai eu la chance de parler \u00e0 des experts du programme Science dans le Nord \u00e0 Oiseaux Canada. Ce num\u00e9ro du Carnet de terrain NB est le r\u00e9sultat de l&rsquo;aventure hivernale qui m&rsquo;a permis d&rsquo;en savoir plus sur nos oiseaux des neiges !<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Par Samuel LeGresley, coordinateur des communications<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10h12<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p class=\"wp-block-paragraph\">Jeudi matin, c&rsquo;est la premi\u00e8re fois que je me rends au Parc Naturel Irving. N&rsquo;ayant pas beaucoup visit\u00e9 Saint-Jean dans ma vie, j&rsquo;ai vu beaucoup de choses nouvelles ce jour-l\u00e0. On roule jusqu&rsquo;au bout de la pointe, sur une grande plage typique de la c\u00f4te de Fundy. J&rsquo;ai vu beaucoup de ces plages, puisque je viens de Moncton et que je suis all\u00e9e \u00e0 Cap-Enrag\u00e9 plusieurs fois, mais cette tranche de c\u00f4te est particuli\u00e8rement belle.<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9382-1-1024x768.jpg\" alt=\"\" class=\"wp-image-19514\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9382-1-1024x768.jpg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9382-1-300x225.jpg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9382-1-768x576.jpg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9382-1-1536x1152.jpg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9382-1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p class=\"wp-block-paragraph\">En sortant de la voiture, je remarque imm\u00e9diatement une \u00eele au loin. Lauren me dit que les oiseaux de rivage s&rsquo;y rendent en \u00e9t\u00e9. J&rsquo;ai ensuite appris qu&rsquo;elle se nomme Manawagonish et qu&rsquo;il s&rsquo;agit d&rsquo;une r\u00e9serve naturelle.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\">\n<p class=\"wp-block-paragraph\">\u00c0 l&rsquo;arri\u00e8re-plan de l&rsquo;\u00eele, deux \u00e9normes navires se dirigent probablement vers ou depuis le port de Saint-Jean.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous observons quelques go\u00e9lands dans la longue vue et pouvons regarder les navires de plus pr\u00e8s en m\u00eame temps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lauren sort un carnet de notes de son sac et commence \u00e0 faire des marques pr\u00e9cises sur le papier. Elle constate que le temps est nuageux et que l&rsquo;eau est inhabituellement calme. C&rsquo;est aussi l&rsquo;heure de la mar\u00e9e basse, qui fait para\u00eetre la plage beaucoup plus grande !<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"1024\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9377-992x1024.jpeg\" alt=\"\" class=\"wp-image-19516\" style=\"width:519px;height:auto\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9377-992x1024.jpeg 992w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9377-291x300.jpeg 291w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9377-768x792.jpeg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9377-1489x1536.jpeg 1489w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9377.jpeg 1985w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9366-1-1024x768.jpg\" alt=\"\" class=\"wp-image-19518\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9366-1-1024x768.jpg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9366-1-300x225.jpg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9366-1-768x576.jpg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9366-1-1536x1152.jpg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9366-1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">Je remarque imm\u00e9diatement un point noir au loin. Et <em>plouf<\/em>, il est hors de vue. Ce doit \u00eatre un canard plongeur en train de se nourrir. Pas si facile \u00e0 identifier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous nous attardons un peu. Le point noir ne r\u00e9appara\u00eet pas. Il doit \u00eatre en train de manger tous les poissons qui vivent l\u00e0.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10h50<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">Nous nous rendons \u00e0 la plage de MacLaren. C&rsquo;est une belle anse, mais il n&rsquo;y a pas beaucoup d&rsquo;oiseaux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A part quelques canards noirs lointains, le seul \u00ab oiseau \u00bb que nous voyons \u00e0 proximit\u00e9 est un oiseau sculpt\u00e9 dans du bois de gr\u00e8ve par l&rsquo;oc\u00e9an.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9386-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-19520\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9386-1-1024x768.jpeg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9386-1-300x225.jpeg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9386-1-768x576.jpeg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9386-1-1536x1152.jpeg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9386-1-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Un <em>oiseau<\/em>, certainement non migrateur, en bois de gr\u00e8ve.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>11h19<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est temps de prendre un d\u00eener pr\u00e9coce. Une belle matin\u00e9e, avec seulement quelques oiseaux qui entrent et sortent de l&rsquo;eau. Cependant, un faible nombre de donn\u00e9es est toujours indicateur de quelque chose.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Les <em>Reversing Falls<\/em>, une manne pour les amateurs de canards<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>12h30<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le repas de midi est termin\u00e9. On arrive sur une falaise, et c&rsquo;est la premi\u00e8re fois que je vois les fameuses<em> Reversing Falls<\/em> (Chutes r\u00e9versibles).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9391-1024x768.jpeg\" alt=\"\" class=\"wp-image-19526\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9391-1024x768.jpeg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9391-300x225.jpeg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9391-768x576.jpeg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9391-1536x1152.jpeg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9391-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p class=\"wp-block-paragraph\">On me dit qu&rsquo;ils sont sur le point de se <em>renverser<\/em>, donc je demande \u00ab Oh, est-ce qu&rsquo;on peut rester dans le coin ? \u00bb. Mais ce n&rsquo;est pas comme le mascaret de Moncton : \u00ab Il faut environ 1 \u00e0 2 heures pour que \u00e7a se renverse \u00bb, explique Lauren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imm\u00e9diatement, nous tombons sur une b\u00e9n\u00e9vole qui a d\u00e9j\u00e0 compt\u00e9 tous les oiseaux pendant sa pause d\u00e9jeuner. Elle \u00e9num\u00e8re toutes les macreuses (des dizaines !) et les harles (encore plus !) qu&rsquo;elle a vus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il s&rsquo;agit de migrateurs de l&rsquo;Arctique, ce qui a suscit\u00e9 mon int\u00e9r\u00eat lors d&rsquo;une discussion avec un expert de Birds Canada. Le fait que ces oiseaux viennent de l&rsquo;Arctique pour \u00e9chapper au manque de nourriture et\/ou \u00e0 la glace de mer omnipr\u00e9sente, dans de nombreux cas, me fait appr\u00e9cier le fait que nous puissions les voir.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9396-1024x768.jpeg\" alt=\"\" class=\"wp-image-19530\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9396-1024x768.jpeg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9396-300x225.jpeg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9396-768x576.jpeg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9396-1536x1152.jpeg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9396-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">Alors que nous balayions l&rsquo;eau du regard, je ne pouvais m&#8217;emp\u00eacher de me demander ce qui poussait ces oiseaux \u00e0 quitter l&rsquo;Arctique chaque ann\u00e9e. J&rsquo;ai appris que la r\u00e9ponse est plus complexe que la simple volont\u00e9 de se sauver du froid.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">Cependant, ils ne viennent pas tous du Grand Nord. L&rsquo;un des oiseaux les plus impressionnants que nous voyons est le Petit garrot, alors que je lis les cartes des aires de r\u00e9partition. Il s&rsquo;agit en fait d&rsquo;un nicheur bor\u00e9al, qui ne se rend pas jusqu&rsquo;\u00e0 l&rsquo;Arctique.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"966\" height=\"670\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/large-23-1.jpg\" alt=\"\" class=\"wp-image-19528\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/large-23-1.jpg 966w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/large-23-1-300x208.jpg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/large-23-1-768x533.jpg 768w\" sizes=\"auto, (max-width: 966px) 100vw, 966px\" \/><figcaption class=\"wp-element-caption\">Un Petit garrot, un oiseau estivant de la for\u00eat bor\u00e9ale, vu pr\u00e8s des <em>Reversing Falls<\/em> \u00e0 Saint-Jean, au Nouveau-Brunswick. <em>Cr\u00e9dit photo : Jimmy Dee<\/em><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">Nous voyons quelques garrots \u00e0 \u0153il d&rsquo;or, beaucoup de harles et de macreuses noires, et quelques Canards noirs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir pass\u00e9 un peu de temps \u00e0 observer tous les oiseaux qui plongent pr\u00e8s des chutes et de l&rsquo;usine de p\u00e2tes et papiers, on range tout dans la voiture, Lauren fait son d\u00e9compte et nous nous dirigeons vers Five Fathom Hole.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9405-1024x768.jpeg\" alt=\"\" class=\"wp-image-19532\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9405-1024x768.jpeg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9405-300x225.jpeg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9405-768x576.jpeg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9405-1536x1152.jpeg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9405-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1:20<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">Nous passons d&rsquo;une rivi\u00e8re \u00e0 l&rsquo;autre : <em>Reversing Falls <\/em>\u00e9tait \u00e0 l&#8217;embouchure de la Wolastoq, et Five Fathom Hole est notre dernier arr\u00eat, \u00e0 l&rsquo;estuaire de la Musquash.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les bateaux, nous trouvons tr\u00e8s peu d&rsquo;oiseaux, mais mon premier voyage aux chutes a suffi \u00e0 faire ma journ\u00e9e. En tout, nous avons compt\u00e9 315 oiseaux, dont 223 rien qu&rsquo;\u00e0<em> Reversing Falls <\/em>!<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9408-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-19534\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9408-1-1024x768.jpeg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9408-1-300x225.jpeg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9408-1-768x576.jpeg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9408-1-1536x1152.jpeg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/IMG_9408-1-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La migration hivernale de l&rsquo;Arctique : plus qu&rsquo;une simple \u00e9vasion du froid<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;id\u00e9e de cet article m&rsquo;a soudainement frapp\u00e9 alors que je lisais A Naturalist&rsquo;s Guide to the Arctic (Guide du naturaliste \u00e0 l&rsquo;Arctique), un livre publi\u00e9 en 1995 par l&rsquo;\u00e9cologiste britannique E. C. Pielou, trouv\u00e9 au magasin local de livres d&rsquo;occasion. J&rsquo;ai remarqu\u00e9 que plusieurs des oiseaux mentionn\u00e9s dans le livre sont pr\u00e9sents au Nouveau-Brunswick en hiver ! Pour commencer mes recherches, j&rsquo;ai contact\u00e9 Cl\u00e9a Frapin, une experte de la faune arctique qui travaille maintenant chez Oiseaux Canada en tant que biologiste du programme Science dans le Nord, puis nous avons eu une longue discussion sur les interactions entre les esp\u00e8ces terrestres de l&rsquo;Arctique. Dans le cadre de sa ma\u00eetrise, elle a construit un mod\u00e8le permettant de pr\u00e9dire les r\u00e9seaux trophiques (cha\u00eene alimentaire) de la faune arctique, et les aspects de la saisonnalit\u00e9 qui poussent de nombreux oiseaux aquatiques et oiseaux de proie, entre autres, \u00e0 se rendre au Nouveau-Brunswick.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cela m&rsquo;a ensuite amen\u00e9 \u00e0 discuter avec Graham Sorenson, gestionnaire du programme Science dans le Nord, \u00e9galement chez Oiseaux Canada, qui m&rsquo;a expliqu\u00e9 la relation fascinante entre la glace de mer et la disponibilit\u00e9 de la nourriture pour les canards de mer.<br>C&rsquo;est gr\u00e2ce \u00e0 ces discussions que j&rsquo;ai pu en apprendre plus sur ces sauvagines qui m&rsquo;intriguaient autant !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La migration de nos visiteurs d&rsquo;hiver, pas seulement d\u00e9termin\u00e9e par la temp\u00e9rature<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pour de nombreux oiseaux de l&rsquo;Arctique, la survie d\u00e9pend de leur capacit\u00e9 \u00e0 trouver de la nourriture, et les sch\u00e9mas de migration refl\u00e8tent les changements dans l&rsquo;abondance des proies, la production de graines et l&rsquo;\u00e9tat de la glace de mer, plut\u00f4t que d&rsquo;\u00e9chapper simplement aux temp\u00e9ratures extr\u00eames.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab L&rsquo;observation des oiseaux en hiver est assez amusante car il y a un m\u00e9lange d&rsquo;esp\u00e8ces qui sont r\u00e9sidentes ici, comme les m\u00e9sanges et les geais bleus (\u2026) Ce qui est excitant, c&rsquo;est que ces esp\u00e8ces ne sont observ\u00e9es qu&rsquo;en tant que visiteurs hivernaux \u00bb. <em>&#8211; Graham Sorenson<\/em><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/SnowyOwl2_FrankBranch-1024x768.jpg\" alt=\"\" class=\"wp-image-19542\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/SnowyOwl2_FrankBranch-1024x768.jpg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/SnowyOwl2_FrankBranch-300x225.jpg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/SnowyOwl2_FrankBranch-768x576.jpg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/SnowyOwl2_FrankBranch.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Un Harfang des neiges. <em>Photo : Frank Branch<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">L&rsquo;un des exemples les plus frappants est celui du Harfang des neiges, dont les mouvements de population sont \u00e9troitement li\u00e9s aux cycles des lemmings dans l&rsquo;Arctique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Un tr\u00e8s bon \u00e9t\u00e9 de lemmings dans le nord entra\u00eene une tr\u00e8s bonne ann\u00e9e de reproduction pour le Harfang des neiges. Parce qu&rsquo;ils sont plus nombreux, certains s&rsquo;enfuient vers le sud. (\u2026) Et ce sont souvent les jeunes qui viennent tr\u00e8s, tr\u00e8s loin au sud. \u00bb <em>-Sorenson<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque trop de jeunes harfangs sont n\u00e9s, certains d&rsquo;entre eux \u00ab d\u00e9bordent \u00bb vers le sud dans ce que les ornithologues appellent une ann\u00e9e d&rsquo;irruption.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que des rapaces comme la Buse pattue se d\u00e9placent vers le sud \u00e0 la recherche de proies, leur migration est souvent due \u00e0 une p\u00e9nurie de proies plut\u00f4t qu&rsquo;\u00e0 une explosion d\u00e9mographique, contrairement au Harfang des neiges.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<p class=\"wp-block-paragraph\">Pour de nombreux oiseaux mangeurs de graines, la disponibilit\u00e9 de la nourriture dans la for\u00eat bor\u00e9ale est le principal d\u00e9clencheur de la migration. Des esp\u00e8ces comme le Bec-crois\u00e9 des sapins, le Tarin des pins et le Gros-bec errant resteront dans le nord si les r\u00e9coltes de c\u00f4nes sont abondantes, mais lorsque la nourriture se fait rare, ils se d\u00e9placent en grand nombre vers le sud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Dans des endroits comme le Nouveau-Brunswick o\u00f9 il y a beaucoup de for\u00eats de conif\u00e8res, nous avons des Gros-becs errants, des Becs-crois\u00e9s des sapins, des Becs-crois\u00e9s bifasci\u00e9s et des Tarins des pins en plus grand nombre, ainsi que certaines esp\u00e8ces de roselins qui sont vraiment impressionnantes \u00e0 voir. On ne les voit pas forc\u00e9ment tous les hivers ; je pense que ce sont celles que les ornithologues appr\u00e9cient le plus lors des ann\u00e9es \u00e0 irruption. \u00bb <em>&#8211; Sorenson<\/em><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"738\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/WHITE-WINGED-CROSSBILL-MALE.-MAR.-09-2022.-BRIAN-STONE-1024x738.jpg\" alt=\"\" class=\"wp-image-19568\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/WHITE-WINGED-CROSSBILL-MALE.-MAR.-09-2022.-BRIAN-STONE-1024x738.jpg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/WHITE-WINGED-CROSSBILL-MALE.-MAR.-09-2022.-BRIAN-STONE-300x216.jpg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/WHITE-WINGED-CROSSBILL-MALE.-MAR.-09-2022.-BRIAN-STONE-768x554.jpg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/WHITE-WINGED-CROSSBILL-MALE.-MAR.-09-2022.-BRIAN-STONE-1536x1107.jpg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/WHITE-WINGED-CROSSBILL-MALE.-MAR.-09-2022.-BRIAN-STONE.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Bec-crois\u00e9 bifasci\u00e9. <em>Photo : Brian Stone<\/em><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pour les sauvagines, la glace d\u00e9termine leur lieu d&rsquo;hivernage<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les sauvagines et les canards de mer, la migration est davantage dict\u00e9e par la couverture de glace que par la temp\u00e9rature elle-m\u00eame. Contrairement aux esp\u00e8ces terrestres qui suivent la disponibilit\u00e9 de la nourriture, les canards, les harles et les garrots ont besoin d&rsquo;eau libre pour survivre.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-1024x746.jpg\" alt=\"\" class=\"wp-image-19540\" style=\"object-fit:cover\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-1024x746.jpg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-300x218.jpg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-768x559.jpg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-1536x1118.jpg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-scaled.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Des Hareldes kakawis. <em>Photo : Pierre Janin<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">\u00ab Un Harelde kakawi peut encore trouver de la nourriture dans le nord, mais les eaux sont gel\u00e9es. Ils doivent se rendre suffisamment loin au sud pour trouver des eaux libres o\u00f9 ils peuvent plonger pour trouver de la nourriture. \u00bb <em>-Sorenson<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cela signifie que certains oiseaux cessent de migrer lorsqu&rsquo;ils atteignent les eaux libres de glace, au lieu de poursuivre leur route vers le sud pour se r\u00e9chauffer. Par exemple, la baie de Fundy reste libre de glace tout au long de l&rsquo;hiver en raison des fortes mar\u00e9es, ce qui constitue un habitat crucial pour de nombreuses esp\u00e8ces. Les garrots et les hareldes restent dans des endroits comme la baie de Fundy parce que les mar\u00e9es maintiennent l&rsquo;eau ouverte, m\u00eame en hiver. C&rsquo;est une question d&rsquo;acc\u00e8s \u00e0 la nourriture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p class=\"wp-block-paragraph\">Certains canards de mer ont tendance \u00e0 hiverner dans le nord du Nouveau-Brunswick, o\u00f9 les conditions restent favorables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Il y a beaucoup de Garrots d&rsquo;Islande qui hivernent dans le nord du Nouveau-Brunswick, mais peu dans la baie de Fundy. Ils aiment les c\u00f4tes rocheuses du nord du Nouveau-Brunswick. \u00bb <em>-Sorenson<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre-temps, des oiseaux de rivage comme le B\u00e9casseau violet profitent des vasi\u00e8res de la baie de Fundy, qui restent accessibles en hiver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Il y a donc des esp\u00e8ces comme le B\u00e9casseau violet et m\u00eame le B\u00e9casseau sanderling qui, sur la c\u00f4te sud de la Nouvelle-\u00c9cosse et peut-\u00eatre sur certaines parties de la c\u00f4te sud du Nouveau-Brunswick, peuvent passer l&rsquo;hiver ici parce qu&rsquo;il y a des vasi\u00e8res ouvertes et des possibilit\u00e9s d&rsquo;alimentation pour les oiseaux de rivage. Je ne pense pas que ce soit le cas dans le golfe du Saint-Laurent et m\u00eame sur la c\u00f4te nord du Nouveau-Brunswick&nbsp;\u00bb, dit Graham.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Suivre les migrations : Ce que les cartes r\u00e9v\u00e8lent<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"wp-block-paragraph\">M. Sorenson et d&rsquo;autres scientifiques utilisent des outils comme eBird pour savoir o\u00f9 les oiseaux migrateurs de l&rsquo;Arctique et de la r\u00e9gion bor\u00e9ale s&rsquo;installent en hiver. Ces cartes fournissent des informations pr\u00e9cieuses sur la mani\u00e8re dont les diff\u00e9rentes esp\u00e8ces d&rsquo;oiseaux r\u00e9agissent \u00e0 la fluctuation des sources de nourriture et \u00e0 l&rsquo;\u00e9tat des glaces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il sort une carte sur le populaire site de science communautaire et me montre comment faire pour voir les donn\u00e9es sp\u00e9cifiques par esp\u00e8ce. \u00ab Si vous vous int\u00e9ressez \u00e0 une esp\u00e8ce comme le Garrot d&rsquo;Islande, vous pouvez consulter eBird et voir qu&rsquo;ils restent principalement (pr\u00e8s) du nord du Nouveau-Brunswick en ce moment. Les points rouges sur la carte indiquent les observations r\u00e9centes, et il est clair qu&rsquo;ils hivernent l\u00e0-haut \u00bb. Des recherches ont montr\u00e9 que sur la c\u00f4te Est, cet oiseau est g\u00e9n\u00e9ralement un nicheur bor\u00e9al, mais qu&rsquo;il peut aller muer \u00e0 des latitudes plus \u00e9lev\u00e9es dans l&rsquo;Arctique (<a href=\"https:\/\/academic.oup.com\/auk\/article\/119\/3\/676\/5561927?login=false\">source<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur eBird, le type de donn\u00e9es en temps r\u00e9el fournies par la communaut\u00e9 aide les chercheurs \u00e0 surveiller les populations d&rsquo;oiseaux, \u00e0 comprendre les sch\u00e9mas de migration et \u00e0 identifier les principales zones d&rsquo;hivernage.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Barrows-Goldeneye-Jim-Clifford-1024x682.jpg\" alt=\"\" class=\"wp-image-19536\" srcset=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Barrows-Goldeneye-Jim-Clifford-1024x682.jpg 1024w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Barrows-Goldeneye-Jim-Clifford-300x200.jpg 300w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Barrows-Goldeneye-Jim-Clifford-768x512.jpg 768w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Barrows-Goldeneye-Jim-Clifford-1536x1024.jpg 1536w, https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Barrows-Goldeneye-Jim-Clifford.jpg 1745w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Le Garrot d&rsquo;Islande, un visiteur hivernal du nord du Nouveau-Brunswick. Photo : Jim Clifford<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/ebird.org\/map\/bargol?neg=true&amp;env.minX=&amp;env.minY=&amp;env.maxX=&amp;env.maxY=&amp;zh=false&amp;gp=false&amp;ev=Z&amp;excludeExX=false&amp;excludeExAll=false&amp;mr=1-12&amp;bmo=1&amp;emo=12&amp;yr=cur\" target=\"_blank\" rel=\"noreferrer noopener\">Sur eBird &#8211; le Garrot d&rsquo;Islande observ\u00e9 dans le N.-B. cette ann\u00e9e<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment participer : Les sciences communautaires pour observer les oiseaux tout au long de l&rsquo;ann\u00e9e<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez contribuer au suivi des oiseaux migrateurs de l&rsquo;Arctique ou d&rsquo;autres oiseaux dans les ann\u00e9es \u00e0 venir, vous pouvez participer \u00e0 des projets de science communautaires qui fournissent des donn\u00e9es pr\u00e9cieuses pour les efforts de conservation tout au long de l&rsquo;ann\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">eBird est un outil puissant qui permet aux ornithologues d&rsquo;enregistrer leurs observations et de suivre les d\u00e9placements des esp\u00e8ces en temps r\u00e9el. Vous pouvez l&rsquo;utiliser pour:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Enregistrer vos observations saisonni\u00e8res d&rsquo;oiseaux au Nouveau-Brunswick ou ailleurs.<\/li>\n\n\n\n<li>Explorer des cartes interactives pour voir o\u00f9 les oiseaux hivernent.<\/li>\n\n\n\n<li>Contribuer aux efforts mondiaux de recherche sur la migration des oiseaux.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Vous pouvez consulter eBird et voir les derni\u00e8res observations de migrateurs arctiques dans votre r\u00e9gion. C&rsquo;est un outil extraordinaire pour les scientifiques et les ornithologues. \u00bb &#8211; Graham Sorenson<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Commencez avec eBird : <a href=\"https:\/\/ebird.org\/\"> ebird.org<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">2. <strong>S&rsquo;associer aux efforts d&rsquo;un recensement sur les oiseaux aquatiques<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Au Port de Saint-Jean et au Port de Belledune, Nature NB organise des recensements visant \u00e0 surveiller la sauvagine et les oiseaux marins hivernant le long de la c\u00f4te. Ces projets visent \u00e0 faire participer les ornithologues locaux \u00e0 des efforts de surveillance structur\u00e9s l\u00e0 o\u00f9 il y a beaucoup d&rsquo;activit\u00e9s humaines susceptibles de perturber les oiseaux dans leur habitat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous \u00eates dans la r\u00e9gion et que vous voulez contribuer, consultez les possibilit\u00e9s de recensement sur la <a href=\"https:\/\/www.naturenb.ca\/fr\/recensement-des-oiseaux-aquatiques-du-port-de-saint-john\/?lang=fr\">page des recensements d&rsquo;oiseaux aquatiques de NatureNB<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Il est important d&rsquo;essayer de couvrir l&rsquo;ensemble de la province, c&rsquo;est pourquoi des efforts tels que les enqu\u00eates sur les oiseaux aquatiques du port de Saint John et de Belledune nous aident \u00e0 suivre les tendances r\u00e9gionales en mati\u00e8re de migration des oiseaux de l&rsquo;Arctique&nbsp;\u00bb &#8211; Graham Sorenson<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Une histoire de migration complexe<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En bref, la migration des oiseaux des climats nordiques vers notre r\u00e9gion n&rsquo;a pas pour seul but d&rsquo;\u00e9chapper au froid hivernal. Il s&rsquo;agit d&rsquo;une strat\u00e9gie de survie hautement sp\u00e9cialis\u00e9e qui d\u00e9pend de la disponibilit\u00e9 de la nourriture, de la couverture de glace et des conditions de l&rsquo;habitat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Tout est li\u00e9 \u00e0 la nourriture, mais il y a deux raisons tr\u00e8s diff\u00e9rentes pour lesquelles ils se d\u00e9placent. Certains descendent vers le sud en raison d&rsquo;une p\u00e9nurie de proies, d&rsquo;autres en raison d&rsquo;une abondance de proies. Et pour les oiseaux aquatiques, tout d\u00e9pend de l&rsquo;endroit o\u00f9 ils peuvent encore trouver de l&rsquo;eau libre. \u00bb &#8211; Graham Sorenson<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les ornithologues, l&rsquo;hiver offre une occasion unique d&rsquo;observer ces incroyables migrateurs du Nord. Il nous offre une fen\u00eatre, aussi petite soit-elle, sur le monde complexe de la migration des oiseaux d&rsquo;Arctique et de la for\u00eat bor\u00e9ale.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.oiseauxcanada.org\/conserver-les-oiseaux\/la-science-dans-le-nord\" target=\"_blank\" rel=\"noreferrer noopener\">En savoir plus sur Science dans le Nord &#8211; Oiseaux Canada<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participez \u00e0 nos efforts scientifiques communautaires en cliquant sur le lien ci-dessous :<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.naturenb.ca\/fr\/science-communautaire\/?lang=fr\">Nature NB et la science communautaire<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis que j&rsquo;ai commenc\u00e9 \u00e0 m&rsquo;int\u00e9resser plus s\u00e9rieusement aux oiseaux, les oiseaux aquatiques m&rsquo;ont toujours un peu intimid\u00e9. Tant de canards \u00e0 apprendre, si peu de temps, me disais-je ! Jusqu&rsquo;\u00e0 ce que je r\u00e9alise que j&rsquo;ai toute la vie devant moi pour apprendre \u00e0 les conna\u00eetre. Je me suis donc rendu \u00e0 Saint John pour en apprendre davantage sur les enqu\u00eates relatives aux oiseaux d&rsquo;eau, en suivant ma coll\u00e8gue Lauren. <\/p>\n","protected":false},"author":2,"featured_media":19541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[620],"tags":[749,195,346,748,745,746,744,747],"class_list":["post-19571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carnet-de-terrain-nb","tag-arctique","tag-nature-nb","tag-nouveau-brunswick","tag-ornithologie","tag-releve-des-oiseaux-deau","tag-saint-jean","tag-sauvagine","tag-science-communautaire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compter tous les canards d&#039;hiver : surveillance des sauvagines et migrants arctiques - Nature NB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compter tous les canards d&#039;hiver : surveillance des sauvagines et migrants arctiques - Nature NB\" \/>\n<meta property=\"og:description\" content=\"Depuis que j&#039;ai commenc\u00e9 \u00e0 m&#039;int\u00e9resser plus s\u00e9rieusement aux oiseaux, les oiseaux aquatiques m&#039;ont toujours un peu intimid\u00e9. Tant de canards \u00e0 apprendre, si peu de temps, me disais-je ! Jusqu&#039;\u00e0 ce que je r\u00e9alise que j&#039;ai toute la vie devant moi pour apprendre \u00e0 les conna\u00eetre. Je me suis donc rendu \u00e0 Saint John pour en apprendre davantage sur les enqu\u00eates relatives aux oiseaux d&#039;eau, en suivant ma coll\u00e8gue Lauren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Nature NB\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-04T16:38:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-06T13:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SymbioTIC Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"SymbioTIC Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/\"},\"author\":{\"name\":\"SymbioTIC Admin\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#\\\/schema\\\/person\\\/3bb9896f4ebf775d808b3206795cc387\"},\"headline\":\"Compter tous les canards d&rsquo;hiver : surveillance des sauvagines et migrants arctiques\",\"datePublished\":\"2025-03-04T16:38:30+00:00\",\"dateModified\":\"2025-03-06T13:23:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/\"},\"wordCount\":2844,\"publisher\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.naturenb.ca\\\/sites\\\/www.naturenb.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Harelde-kakawi-en-groupe-scaled.jpg\",\"keywords\":[\"arctique\",\"nature nb\",\"nouveau-brunswick\",\"ornithologie\",\"relev\u00e9 des oiseaux d'eau\",\"saint-jean\",\"sauvagine\",\"science communautaire\"],\"articleSection\":[\"Carnet de terrain NB\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/\",\"url\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/\",\"name\":\"Compter tous les canards d'hiver : surveillance des sauvagines et migrants arctiques - Nature NB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.naturenb.ca\\\/sites\\\/www.naturenb.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Harelde-kakawi-en-groupe-scaled.jpg\",\"datePublished\":\"2025-03-04T16:38:30+00:00\",\"dateModified\":\"2025-03-06T13:23:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.naturenb.ca\\\/sites\\\/www.naturenb.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Harelde-kakawi-en-groupe-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.naturenb.ca\\\/sites\\\/www.naturenb.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Harelde-kakawi-en-groupe-scaled.jpg\",\"width\":2560,\"height\":1864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compter tous les canards d&rsquo;hiver : surveillance des sauvagines et migrants arctiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/\",\"name\":\"Nature NB\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#organization\",\"name\":\"Nature NB\",\"url\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.naturenb.ca\\\/sites\\\/www.naturenb.ca\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/NatureNB_Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.naturenb.ca\\\/sites\\\/www.naturenb.ca\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/NatureNB_Logo-1.png\",\"width\":\"1200\",\"height\":\"750\",\"caption\":\"Nature NB\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/#\\\/schema\\\/person\\\/3bb9896f4ebf775d808b3206795cc387\",\"name\":\"SymbioTIC Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c814fab14c6f67203ba004949d615c276cacbd371139d6fec0a2564346ebb65e?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c814fab14c6f67203ba004949d615c276cacbd371139d6fec0a2564346ebb65e?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c814fab14c6f67203ba004949d615c276cacbd371139d6fec0a2564346ebb65e?s=96&r=g\",\"caption\":\"SymbioTIC Admin\"},\"url\":\"https:\\\/\\\/www.naturenb.ca\\\/fr\\\/author\\\/shane-symbiotic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compter tous les canards d'hiver : surveillance des sauvagines et migrants arctiques - Nature NB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/","og_locale":"fr_CA","og_type":"article","og_title":"Compter tous les canards d'hiver : surveillance des sauvagines et migrants arctiques - Nature NB","og_description":"Depuis que j'ai commenc\u00e9 \u00e0 m'int\u00e9resser plus s\u00e9rieusement aux oiseaux, les oiseaux aquatiques m'ont toujours un peu intimid\u00e9. Tant de canards \u00e0 apprendre, si peu de temps, me disais-je ! Jusqu'\u00e0 ce que je r\u00e9alise que j'ai toute la vie devant moi pour apprendre \u00e0 les conna\u00eetre. Je me suis donc rendu \u00e0 Saint John pour en apprendre davantage sur les enqu\u00eates relatives aux oiseaux d'eau, en suivant ma coll\u00e8gue Lauren.","og_url":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/","og_site_name":"Nature NB","article_published_time":"2025-03-04T16:38:30+00:00","article_modified_time":"2025-03-06T13:23:58+00:00","og_image":[{"width":2560,"height":1864,"url":"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-scaled.jpg","type":"image\/jpeg"}],"author":"SymbioTIC Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"SymbioTIC Admin","Estimation du temps de lecture":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/#article","isPartOf":{"@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/"},"author":{"name":"SymbioTIC Admin","@id":"https:\/\/www.naturenb.ca\/fr\/#\/schema\/person\/3bb9896f4ebf775d808b3206795cc387"},"headline":"Compter tous les canards d&rsquo;hiver : surveillance des sauvagines et migrants arctiques","datePublished":"2025-03-04T16:38:30+00:00","dateModified":"2025-03-06T13:23:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/"},"wordCount":2844,"publisher":{"@id":"https:\/\/www.naturenb.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-scaled.jpg","keywords":["arctique","nature nb","nouveau-brunswick","ornithologie","relev\u00e9 des oiseaux d'eau","saint-jean","sauvagine","science communautaire"],"articleSection":["Carnet de terrain NB"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/","url":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/","name":"Compter tous les canards d'hiver : surveillance des sauvagines et migrants arctiques - Nature NB","isPartOf":{"@id":"https:\/\/www.naturenb.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/#primaryimage"},"image":{"@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-scaled.jpg","datePublished":"2025-03-04T16:38:30+00:00","dateModified":"2025-03-06T13:23:58+00:00","breadcrumb":{"@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/#primaryimage","url":"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-scaled.jpg","contentUrl":"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-scaled.jpg","width":2560,"height":1864},{"@type":"BreadcrumbList","@id":"https:\/\/www.naturenb.ca\/fr\/compter-tous-les-canards-dhiver-surveillance-des-sauvagines-et-migrants-arctiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naturenb.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Compter tous les canards d&rsquo;hiver : surveillance des sauvagines et migrants arctiques"}]},{"@type":"WebSite","@id":"https:\/\/www.naturenb.ca\/fr\/#website","url":"https:\/\/www.naturenb.ca\/fr\/","name":"Nature NB","description":"","publisher":{"@id":"https:\/\/www.naturenb.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naturenb.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.naturenb.ca\/fr\/#organization","name":"Nature NB","url":"https:\/\/www.naturenb.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.naturenb.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2023\/10\/NatureNB_Logo-1.png","contentUrl":"https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2023\/10\/NatureNB_Logo-1.png","width":"1200","height":"750","caption":"Nature NB"},"image":{"@id":"https:\/\/www.naturenb.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.naturenb.ca\/fr\/#\/schema\/person\/3bb9896f4ebf775d808b3206795cc387","name":"SymbioTIC Admin","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/c814fab14c6f67203ba004949d615c276cacbd371139d6fec0a2564346ebb65e?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c814fab14c6f67203ba004949d615c276cacbd371139d6fec0a2564346ebb65e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c814fab14c6f67203ba004949d615c276cacbd371139d6fec0a2564346ebb65e?s=96&r=g","caption":"SymbioTIC Admin"},"url":"https:\/\/www.naturenb.ca\/fr\/author\/shane-symbiotic\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-scaled.jpg",2560,1864,false],"thumbnail":["https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-150x150.jpg",150,150,true],"medium":["https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-300x218.jpg",300,218,true],"medium_large":["https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-768x559.jpg",768,559,true],"large":["https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-1024x746.jpg",1024,746,true],"1536x1536":["https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-1536x1118.jpg",1536,1118,true],"2048x2048":["https:\/\/www.naturenb.ca\/sites\/www.naturenb.ca\/wp-content\/uploads\/2025\/03\/Harelde-kakawi-en-groupe-2048x1491.jpg",2048,1491,true]},"uagb_author_info":{"display_name":"SymbioTIC Admin","author_link":"https:\/\/www.naturenb.ca\/fr\/author\/shane-symbiotic\/"},"uagb_comment_info":0,"uagb_excerpt":"Depuis que j'ai commenc\u00e9 \u00e0 m'int\u00e9resser plus s\u00e9rieusement aux oiseaux, les oiseaux aquatiques m'ont toujours un peu intimid\u00e9. Tant de canards \u00e0 apprendre, si peu de temps, me disais-je ! Jusqu'\u00e0 ce que je r\u00e9alise que j'ai toute la vie devant moi pour apprendre \u00e0 les conna\u00eetre. Je me suis donc rendu \u00e0 Saint John&hellip;","_links":{"self":[{"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/posts\/19571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/comments?post=19571"}],"version-history":[{"count":4,"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/posts\/19571\/revisions"}],"predecessor-version":[{"id":19643,"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/posts\/19571\/revisions\/19643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/media\/19541"}],"wp:attachment":[{"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/media?parent=19571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/categories?post=19571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.naturenb.ca\/fr\/wp-json\/wp\/v2\/tags?post=19571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}